{"id":9970,"date":"2024-03-07T09:52:24","date_gmt":"2024-03-07T09:52:24","guid":{"rendered":"https:\/\/protoandgo.com\/2024\/03\/07\/donne-e-stampa-3d\/"},"modified":"2026-01-27T07:32:33","modified_gmt":"2026-01-27T07:32:33","slug":"donne-e-stampa-3d","status":"publish","type":"post","link":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/","title":{"rendered":"Donne e stampa 3D"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9970\" class=\"elementor elementor-9970 elementor-9903\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5447f8fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5447f8fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b941381\" data-id=\"7b941381\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa1e29 elementor-widget elementor-widget-text-editor\" data-id=\"aa1e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per commemorare l&#8217;8 marzo, <strong>Giornata internazionale della donna<\/strong>, noi di <a href=\"https:\/\/protoandgo.com\/it\/\" target=\"_blank\" rel=\"noopener\">Proto&amp;Go!<\/a> vogliamo concentrarci su donne significative nella storia della <strong>stampa 3D<\/strong>. <\/p>\n<p>Oggi sempre pi\u00f9 donne padroneggiano la tecnologia di <b><a href=\"https:\/\/protoandgo.com\/it\/stampa-3d\/\">produzione additiva<\/a><\/b> e sono impegnate in settori come quello aerospaziale, automobilistico, medico, del design e dell&#8217;istruzione. <\/p>\n<p>In questo articolo vi raccontiamo come le donne hanno contribuito a diversi settori, spinte dalla loro passione per le nuove tecnologie e l&#8217;innovazione. <\/p>\n<h2><strong>Neri Oxman, leader nella progettazione biologica<\/strong> <\/h2>\n<p>Neri Oxman \u00e8 designer, architetto e direttore del gruppo di ricerca Mediated Matter del MIT. Ha ricercato e sviluppato nuovi materiali e processi per la <b><a href=\"https:\/\/protoandgo.com\/it\/stampa-3d-cose-e-come-funziona\/\">stampa 3D<\/a><\/b>, compresa la <strong>stampa 3D<\/strong> del vetro e di altri materiali compositi. <\/p>\n<p>La designer ha sempre concluso i suoi primi progetti con la creazione di un mobile utile, un pezzo di tessuto o qualsiasi altro oggetto. Una delle caratteristiche principali dei suoi progetti \u00e8 che hanno sempre un indiscutibile valore estetico e scientifico. Tuttavia, per Oxman, il design che pensa solo ad abbellire il mondo non sopravviver\u00e0, quindi \u00e8 necessario indagare e capire come funziona la natura per adattarsi ad essa (essendo allo stesso tempo bello e perfettamente funzionale). <\/p>\n<p>Nel 2015, il suo team ha iniziato a esplorare le possibilit\u00e0 della <strong>stampa 3D<\/strong> con il vetro fuso, poich\u00e9 fino ad allora era stata utilizzata solo la polvere di vetro. Il team ha sviluppato la G3DP, una stampante per vetro otticamente chiaro. Questa macchina, soprannominata &#8220;la macchina per cucire il vetro&#8221;, controlla la trasparenza, il colore, la consistenza e la durezza del processo, permettendo la creazione di pezzi di vetro utilizzabili in architettura e nella fabbricazione di piccoli oggetti. <\/p>\n<p>Sebbene l&#8217;interesse principale di Oxman sia la ricerca di nuovi materiali legati agli organismi viventi, attualmente sta svolgendo anche ricerche per migliorare i materiali convenzionali. <\/p>\n<h2><strong>Nieves Cubo e la bioprinting della pelle<\/strong> <\/h2>\n<p>Nieves Cubo \u00e8 ingegnere, ricercatrice e pioniera nel campo della stampa 3D di tessuti. \u00c8 stato il primo a realizzare pelle umana con una <strong>stampante 3D<\/strong> (utilizzando cellule di pazienti umani). <\/p>\n<p>Uno dei progetti a cui ha partecipato \u00e8 quello sulla prevenzione delle malattie con materiali antimicrobici nei settori alimentare e sanitario, che consisteva nel preparare materiali plastici resistenti alla crescita dei microrganismi. <\/p>\n<p>Negli ultimi anni, il suo lavoro si \u00e8 concentrato sullo sviluppo di nuovi bioinchiostri e processi di deposizione cellulare che consentono di generare nuovi tessuti. L&#8217;obiettivo \u00e8 ottenere sistemi replicabili e a basso costo che possano essere riprodotti in altre parti del mondo e che consentano di ottimizzare i processi di deposizione della <b><a href=\"https:\/\/protoandgo.com\/it\/vantaggi-e-applicazioni-della-stampa-3d\/\">stampa 3D<\/a><\/b><strong> <\/strong>nel tentativo di superare i limiti di questa tecnologia. <\/p>\n<h2><strong>Danit Peleg e la fusione tra moda e stampa 3D<\/strong> <\/h2>\n<p>Danit Peleg \u00e8 una stilista e creatrice del primo capo di abbigliamento stampato in 3D disponibile in commercio. <\/p>\n<p>\u00c8 stata riconosciuta da Forbes come una delle 50 donne pi\u00f9 importanti nel settore tecnologico in Europa. Le sue principali innovazioni sono state legate alla creazione di diversi tessuti con la <strong>stampa 3D<\/strong>. <\/p>\n<p>Ha progettato la sua prima giacca stampata in 3D, chiamata <em>Liberte<\/em>, dopo aver sperimentato diversi materiali e configurazioni. Dopo questo successo iniziale, ha creato altri modelli per formare una collezione completa. <\/p>\n<p>Successivamente, ha avviato il proprio studio, attraverso il quale fornisce progetti personalizzati stampati in 3D per i clienti. <\/p>\n<h2><strong>Il futuro delle donne nella stampa 3D<\/strong> <\/h2>\n<p>Nel complesso, possiamo dire che le donne nel <b><a href=\"https:\/\/protoandgo.com\/it\/qual-e-il-futuro-della-stampa-3d\/\">settore della stampa 3D<\/a><\/b> sono un esempio di perseveranza e determinazione. Nonostante le barriere di genere che ancora esistono nel settore, dimostrano quotidianamente la loro capacit\u00e0 di guidare e creare soluzioni innovative. <\/p>\n<p>La tecnologia della <strong>stampa 3D<\/strong> \u00e8 in continua evoluzione e miglioramento e il contributo delle donne in questo campo \u00e8 fondamentale per il suo continuo sviluppo. <\/p>\n<p>Con lo sviluppo delle <a href=\"https:\/\/protoandgo.com\/it\/tecniche-di-stampa-3d-multi-jet-fusion\/\">tecnologie di produzione additiva<\/a>, si sviluppa anche la partecipazione delle donne. Tuttavia, per raggiungere la parit\u00e0, le barriere di genere nell&#8217;industria tecnologica devono continuare a essere abbattute. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Per commemorare l&#8217;8 marzo, Giornata internazionale della donna, noi di Proto&amp;Go! vogliamo concentrarci su donne significative nella storia della stampa 3D. Oggi sempre pi\u00f9 donne padroneggiano la tecnologia di produzione additiva e sono impegnate in settori come quello aerospaziale, automobilistico, medico, del design e dell&#8217;istruzione. In questo articolo vi raccontiamo come le donne hanno contribuito [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":9918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[148],"tags":[],"class_list":["post-9970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stampa-3d","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stampa 3D: donne di rilievo nel settore<\/title>\n<meta name=\"description\" content=\"Per commemorare la Giornata internazionale della donna, a Proto&amp;Go! sottolineiamo l&#039;importanza delle donne nella storia della stampa 3D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stampa 3D: donne di rilievo nel settore\" \/>\n<meta property=\"og:description\" content=\"Per commemorare la Giornata internazionale della donna, a Proto&amp;Go! sottolineiamo l&#039;importanza delle donne nella storia della stampa 3D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"PROTO&amp;GO!\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T09:52:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T07:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elena L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/\"},\"author\":{\"name\":\"Elena L\u00f3pez\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#\\\/schema\\\/person\\\/c0b0855af12e55c279cea058d6013d1d\"},\"headline\":\"Donne e stampa 3D\",\"datePublished\":\"2024-03-07T09:52:24+00:00\",\"dateModified\":\"2026-01-27T07:32:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/\"},\"wordCount\":639,\"publisher\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg\",\"articleSection\":[\"Stampa 3D\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/\",\"url\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/\",\"name\":\"Stampa 3D: donne di rilievo nel settore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg\",\"datePublished\":\"2024-03-07T09:52:24+00:00\",\"dateModified\":\"2026-01-27T07:32:33+00:00\",\"description\":\"Per commemorare la Giornata internazionale della donna, a Proto&Go! sottolineiamo l'importanza delle donne nella storia della stampa 3D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/donne-e-stampa-3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donne e stampa 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/\",\"name\":\"PROTO&GO!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#organization\",\"name\":\"PROTO&GO!\",\"url\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGOTIPO1.png\",\"contentUrl\":\"https:\\\/\\\/protoandgo.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LOGOTIPO1.png\",\"width\":336,\"height\":88,\"caption\":\"PROTO&GO!\"},\"image\":{\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/protoandgo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/proto-go\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/#\\\/schema\\\/person\\\/c0b0855af12e55c279cea058d6013d1d\",\"name\":\"Elena L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g\",\"caption\":\"Elena L\u00f3pez\"},\"url\":\"https:\\\/\\\/protoandgo.com\\\/it\\\/author\\\/elopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stampa 3D: donne di rilievo nel settore","description":"Per commemorare la Giornata internazionale della donna, a Proto&Go! sottolineiamo l'importanza delle donne nella storia della stampa 3D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/","og_locale":"it_IT","og_type":"article","og_title":"Stampa 3D: donne di rilievo nel settore","og_description":"Per commemorare la Giornata internazionale della donna, a Proto&Go! sottolineiamo l'importanza delle donne nella storia della stampa 3D.","og_url":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/","og_site_name":"PROTO&amp;GO!","article_published_time":"2024-03-07T09:52:24+00:00","article_modified_time":"2026-01-27T07:32:33+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg","type":"image\/jpeg"}],"author":"Elena L\u00f3pez","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Elena L\u00f3pez","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#article","isPartOf":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/"},"author":{"name":"Elena L\u00f3pez","@id":"https:\/\/protoandgo.com\/it\/#\/schema\/person\/c0b0855af12e55c279cea058d6013d1d"},"headline":"Donne e stampa 3D","datePublished":"2024-03-07T09:52:24+00:00","dateModified":"2026-01-27T07:32:33+00:00","mainEntityOfPage":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/"},"wordCount":639,"publisher":{"@id":"https:\/\/protoandgo.com\/it\/#organization"},"image":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg","articleSection":["Stampa 3D"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/","url":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/","name":"Stampa 3D: donne di rilievo nel settore","isPartOf":{"@id":"https:\/\/protoandgo.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#primaryimage"},"image":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg","datePublished":"2024-03-07T09:52:24+00:00","dateModified":"2026-01-27T07:32:33+00:00","description":"Per commemorare la Giornata internazionale della donna, a Proto&Go! sottolineiamo l'importanza delle donne nella storia della stampa 3D.","breadcrumb":{"@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#primaryimage","url":"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg","contentUrl":"https:\/\/protoandgo.com\/wp-content\/uploads\/2024\/03\/a4817b9887ab589f58ea7258b3e4cecbafa126c2_2880x1620-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/protoandgo.com\/it\/donne-e-stampa-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/protoandgo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Donne e stampa 3D"}]},{"@type":"WebSite","@id":"https:\/\/protoandgo.com\/it\/#website","url":"https:\/\/protoandgo.com\/it\/","name":"PROTO&GO!","description":"","publisher":{"@id":"https:\/\/protoandgo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protoandgo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/protoandgo.com\/it\/#organization","name":"PROTO&GO!","url":"https:\/\/protoandgo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/protoandgo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/protoandgo.com\/wp-content\/uploads\/2023\/04\/LOGOTIPO1.png","contentUrl":"https:\/\/protoandgo.com\/wp-content\/uploads\/2023\/04\/LOGOTIPO1.png","width":336,"height":88,"caption":"PROTO&GO!"},"image":{"@id":"https:\/\/protoandgo.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/protoandgo\/","https:\/\/www.linkedin.com\/company\/proto-go\/"]},{"@type":"Person","@id":"https:\/\/protoandgo.com\/it\/#\/schema\/person\/c0b0855af12e55c279cea058d6013d1d","name":"Elena L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/018f0ad95419d0914f36ec296d236ee7f4534a01b2ff31f08204ba798c542e4c?s=96&d=mm&r=g","caption":"Elena L\u00f3pez"},"url":"https:\/\/protoandgo.com\/it\/author\/elopez\/"}]}},"_links":{"self":[{"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/posts\/9970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/comments?post=9970"}],"version-history":[{"count":3,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/posts\/9970\/revisions"}],"predecessor-version":[{"id":12906,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/posts\/9970\/revisions\/12906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/media\/9918"}],"wp:attachment":[{"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/media?parent=9970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/categories?post=9970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protoandgo.com\/it\/wp-json\/wp\/v2\/tags?post=9970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}